{"id":394,"date":"2020-11-27T15:21:06","date_gmt":"2020-11-27T14:21:06","guid":{"rendered":"https:\/\/mammamia.lu\/?post_type=product&#038;p=394"},"modified":"2026-03-21T12:00:35","modified_gmt":"2026-03-21T11:00:35","slug":"tagliatelle-napoli","status":"publish","type":"product","link":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/","title":{"rendered":"Tagliatelle Napoli"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Tagliatelle en Sauce Tomate [1.3]<\/p>\n","protected":false},"featured_media":820,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[77],"product_tag":[],"class_list":{"0":"post-394","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pates-traditionnelles","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria\" \/>\n<meta property=\"og:description\" content=\"Tagliatelle en Sauce Tomate [1.3]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Mamma Mia Ristorante Pizzeria\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-21T11:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/207-Tagliatelle-Napoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/\",\"url\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/\",\"name\":\"Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mammamia.lu\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/207-Tagliatelle-Napoli.jpg\",\"datePublished\":\"2020-11-27T14:21:06+00:00\",\"dateModified\":\"2026-03-21T11:00:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mammamia.lu\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/207-Tagliatelle-Napoli.jpg\",\"contentUrl\":\"https:\\\/\\\/mammamia.lu\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/207-Tagliatelle-Napoli.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/product\\\/tagliatelle-napoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mammamia.lu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mammamia.lu\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tagliatelle Napoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#website\",\"url\":\"https:\\\/\\\/mammamia.lu\\\/\",\"name\":\"Mamma Mia Restaurant Pizzeria\",\"description\":\"Sp\u00e9cialit\u00e9(s) : Fran\u00e7aise , Italienne , \u00e0 emporter\",\"publisher\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mammamia.lu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#organization\",\"name\":\"Restaurant Mamma Mia\",\"url\":\"https:\\\/\\\/mammamia.lu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mammamia.lu\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo_trans.png\",\"contentUrl\":\"https:\\\/\\\/mammamia.lu\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo_trans.png\",\"width\":905,\"height\":231,\"caption\":\"Restaurant Mamma Mia\"},\"image\":{\"@id\":\"https:\\\/\\\/mammamia.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/","og_locale":"fr_FR","og_type":"article","og_title":"Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria","og_description":"Tagliatelle en Sauce Tomate [1.3]","og_url":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/","og_site_name":"Mamma Mia Ristorante Pizzeria","article_modified_time":"2026-03-21T11:00:35+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/207-Tagliatelle-Napoli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/","url":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/","name":"Tagliatelle Napoli - Mamma Mia Ristorante Pizzeria","isPartOf":{"@id":"https:\/\/mammamia.lu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/#primaryimage"},"image":{"@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/#primaryimage"},"thumbnailUrl":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/207-Tagliatelle-Napoli.jpg","datePublished":"2020-11-27T14:21:06+00:00","dateModified":"2026-03-21T11:00:35+00:00","breadcrumb":{"@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/#primaryimage","url":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/207-Tagliatelle-Napoli.jpg","contentUrl":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/207-Tagliatelle-Napoli.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/mammamia.lu\/index.php\/product\/tagliatelle-napoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mammamia.lu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mammamia.lu\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Tagliatelle Napoli"}]},{"@type":"WebSite","@id":"https:\/\/mammamia.lu\/#website","url":"https:\/\/mammamia.lu\/","name":"Mamma Mia Restaurant Pizzeria","description":"Sp\u00e9cialit\u00e9(s) : Fran\u00e7aise , Italienne , \u00e0 emporter","publisher":{"@id":"https:\/\/mammamia.lu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mammamia.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mammamia.lu\/#organization","name":"Restaurant Mamma Mia","url":"https:\/\/mammamia.lu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mammamia.lu\/#\/schema\/logo\/image\/","url":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/logo_trans.png","contentUrl":"https:\/\/mammamia.lu\/wp-content\/uploads\/2020\/11\/logo_trans.png","width":905,"height":231,"caption":"Restaurant Mamma Mia"},"image":{"@id":"https:\/\/mammamia.lu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/product\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/media\/820"}],"wp:attachment":[{"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/product_brand?post=394"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/product_cat?post=394"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mammamia.lu\/index.php\/wp-json\/wp\/v2\/product_tag?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}